{"id":383092,"date":"2025-12-17T19:03:10","date_gmt":"2025-12-17T18:03:10","guid":{"rendered":"https:\/\/lasurprise.hu\/?post_type=product&#038;p=383092"},"modified":"2025-12-17T19:11:15","modified_gmt":"2025-12-17T18:11:15","slug":"kerzenpulver-orange","status":"publish","type":"product","link":"https:\/\/lasurprise.hu\/de\/product-2\/kerzenpulver-orange\/","title":{"rendered":"Kerzenpulver Orange"},"content":{"rendered":"<p><strong>KERZENVORBEREITUNG<\/strong>Gie\u00dfen Sie eine mindestens 5 cm hohe Schicht in ein nicht brennbares Gef\u00e4\u00df. Das Gef\u00e4\u00df muss mindestens 8 cm Durchmesser haben. Stecken Sie den gesamten Docht in die eingestreute Schicht, sodass bei Baumwolldochten 1 cm und bei Holzdochten 2\u20133 mm herausschauen. Z\u00fcnden Sie die Kerze an.<\/p>\n<p><strong>INHALT<\/strong>Option 1: Enth\u00e4lt 250 g granuliertes Wachs und 10 Dochte, Option 2: Enth\u00e4lt 500 g granuliertes Wachs und 20 Dochte.<\/p>\n<p><strong>\u00c4THERISCHES \u00d6L<\/strong> HINZUF\u00dcGEN (DUFT):<\/p>\n<p>Dem Haupt- oder Fl\u00fcssigteil des Wachses k\u00f6nnen \u00e4therische \u00d6le zugesetzt werden.<br \/>\nGeben Sie vor dem Anz\u00fcnden ein paar Tropfen \u00e4therisches \u00d6l hinzu, oder blasen Sie die Kerze, wenn sie brennt, aus, geben Sie die erforderliche Menge \u00e4therisches \u00d6l hinzu und z\u00fcnden Sie sie erneut an.<\/p>\n<p><strong>Zertifiziertes Produkt<\/strong>: Die Gesundheit unserer Kunden hat f\u00fcr uns Priorit\u00e4t. Alle unsere La Surprise-Produkte werden unter Ber\u00fccksichtigung der Sicherheit hergestellt und erf\u00fcllen h\u00f6chste Standards und Zertifizierungen. Sie bestehen aus nat\u00fcrlichen Inhaltsstoffen, brennen ru\u00dffrei und halten deutlich l\u00e4nger als herk\u00f6mmliche Kerzen.<\/p>\n<p><strong>WARNUNG<\/strong>: Lassen Sie eine brennende Kerze niemals unbeaufsichtigt. Halten Sie freistehende, brennende Kerzen von Kindern und Haustieren fern. Halten Sie zwischen brennenden Kerzen immer mindestens 8 cm Abstand. Stellen Sie eine brennende Kerze nicht auf oder in die N\u00e4he von Gegenst\u00e4nden, die leicht Feuer fangen k\u00f6nnen. Bewegen Sie die Kerze nicht, w\u00e4hrend sie brennt. Verzehren Sie keine Kerze oder Kerzenteile! Die Verpackung der PowderCandle-Kerze besteht aus brennbarem Material und ist kein geeigneter Beh\u00e4lter zum Anz\u00fcnden von Kerzen!<\/p>\n<p>Die Kerze ist geruchs- und parf\u00fcmfrei. Sie brennt ru\u00dffrei und hinterl\u00e4sst sauberes Geschirr. Das Wachs ist wasserfest und schwimmf\u00e4hig.<\/p>\n<p>Sobald der Docht abgebrannt ist, warten Sie, bis der Beh\u00e4lter abgek\u00fchlt ist. Entsorgen Sie den harten Teil der Kerze und den Docht.<\/p>","protected":false},"excerpt":{"rendered":"<p>Kerzenpulver ist eine Kerze aus Pflanzenwachs.<br \/>\nOption 1: Enth\u00e4lt 250 g granuliertes Wachs und 10 Dochte.<br \/>\nOption 2: Enth\u00e4lt 500 g granuliertes Wachs und 20 Dochte.<\/p>\n<p>Der Kerzenstaub <strong>einzigartig<\/strong> Und <strong>magisch<\/strong> Weg zu <strong>eine Stimmung erzeugen<\/strong>.<br \/>\nKerzenstaub ist auf seine Art einzigartig. Jede Kerze ist ein Unikat. <strong>mit Liebe handgefertigt<\/strong> Und <strong>mit Sorgfalt hergestellt<\/strong>, also ist es ein kleines Kunstwerk.<br \/>\nJe nach Gr\u00f6\u00dfe des verwendeten Geschirrs k\u00f6nnen bis zu <strong>mehrere Kerzen<\/strong>\u00a0oder\u00a0<strong>Mehrdochtkerzen<\/strong>\u00a0k\u00f6nnen auch gemacht werden.<\/p>","protected":false},"featured_media":383014,"comment_status":"open","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","iawp_total_views":15},"product_brand":[],"product_cat":[541],"product_tag":[],"class_list":["post-383092","product","type-product","status-publish","has-post-thumbnail","product_cat-candledust","product_shipping_class-candles","pa_szarmazasi-orszag-lengyelorszag","pa_szarmazasi-orszag-magyarorszag","first","instock","featured","taxable","shipping-taxable","purchasable","product-type-variable","has-default-attributes","wvs-archive-product-wrapper"],"exclude_global_add_ons":[],"addons":[],"_links":{"self":[{"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/product\/383092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/comments?post=383092"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/media\/383014"}],"wp:attachment":[{"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/media?parent=383092"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/product_brand?post=383092"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/product_cat?post=383092"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/lasurprise.hu\/de\/wp-json\/wp\/v2\/product_tag?post=383092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}